{"id":1267,"date":"2016-09-26T14:03:02","date_gmt":"2016-09-26T12:03:02","guid":{"rendered":"https:\/\/2016.sevilla.wordcamp.org\/?p=1267"},"modified":"2016-09-26T12:44:36","modified_gmt":"2016-09-26T10:44:36","slug":"ponencia-la-importancia-de-la-cache-para-un-proyecto-wordpress","status":"publish","type":"post","link":"https:\/\/sevilla.wordcamp.org\/2016\/ponencia-la-importancia-de-la-cache-para-un-proyecto-wordpress\/","title":{"rendered":"Ponencia: La importancia de la cach\u00e9 para un proyecto WordPress"},"content":{"rendered":"<p>Cu\u00e1ndo comienzas un nuevo proyecto con WordPress, \u00bftienes alguna estrategia definida en cuanto al uso de la cach\u00e9? \u00bfTe gustar\u00eda conocer otros t\u00e9cnicas para acelerar\u00a0la entrega de tus contenidos y mejorar la experiencia de tu usuario?<\/p>\n<p><a href=\"https:\/\/2016.sevilla.wordcamp.org\/speaker\/fernando-puente\/\">Fernando Puente<\/a>\u00a0nos mostrar\u00e1 en esta <a href=\"https:\/\/2016.sevilla.wordcamp.org\/session\/cache-para-un-proyecto-wordpress\/\">ponencia<\/a>\u00a0las estrategias y t\u00e9cnicas relacionadas con el uso de los sistemas y tipos de cach\u00e9 existentes, as\u00ed como las mejoras en optimizaci\u00f3n que supone, desde conceptos b\u00e1sicos para cualquier usuario de Internet como para usuarios medios y avanzados, donde tratar\u00e1\u00a0de sorprender con nuevos puntos de vista.<\/p>\n<p>Fernando tiene 20 a\u00f1os de experiencia en TI.\u00a0Actualmente trabaja\u00a0como Director t\u00e9cnico para La Estrategia de Chapman, una empresa de comunicaci\u00f3n digital y audiovisual con proyecci\u00f3n internacional, donde gestionan, gracias a WordPress, m\u00e1s de 10 millones de visitas al mes, a nivel mundial y en cuatro idiomas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cu\u00e1ndo comienzas un nuevo proyecto con WordPress, \u00bftienes alguna estrategia definida en cuanto al uso de la cach\u00e9? \u00bfTe gustar\u00eda conocer otros t\u00e9cnicas para acelerar\u00a0la entrega de tus contenidos y mejorar la experiencia de tu usuario? Fernando Puente\u00a0nos mostrar\u00e1 en esta ponencia\u00a0las estrategias y t\u00e9cnicas relacionadas con el uso de los sistemas y tipos de &hellip; <a href=\"https:\/\/sevilla.wordcamp.org\/2016\/ponencia-la-importancia-de-la-cache-para-un-proyecto-wordpress\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Ponencia: La importancia de la cach\u00e9 para un proyecto WordPress<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":11274997,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10659,943237],"tags":[],"class_list":["post-1267","post","type-post","status-publish","format-standard","hentry","category-ponencias","category-wordcamp2016"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p72Uuo-kr","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/1267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/11274997"}],"replies":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=1267"}],"version-history":[{"count":1,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/1267\/revisions"}],"predecessor-version":[{"id":1268,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/1267\/revisions\/1268"}],"wp:attachment":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=1267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/categories?post=1267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/tags?post=1267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}