{"id":1499,"date":"2016-09-19T10:03:39","date_gmt":"2016-09-19T08:03:39","guid":{"rendered":"https:\/\/2016.sevilla.wordcamp.org\/?p=1499"},"modified":"2016-09-19T19:21:55","modified_gmt":"2016-09-19T17:21:55","slug":"segundo-dia-de-wcsevilla16-en-la-academia","status":"publish","type":"post","link":"https:\/\/sevilla.wordcamp.org\/2016\/segundo-dia-de-wcsevilla16-en-la-academia\/","title":{"rendered":"Segundo d\u00eda de #WCSevilla16 en la Academia"},"content":{"rendered":"<p>\u00bfDespu\u00e9s del fin de semana ya te has decidido venir a WordCamp Sevilla 2016? Revisa\u00a0el <a href=\"https:\/\/2016.sevilla.wordcamp.org\/programacion\/\" target=\"_blank\">programa<\/a>\u00a0y aprovecha\u00a0la oportunidad.<\/p>\n<p>Como ya comentamos a finales de semana c\u00f3mo ser\u00e1 el\u00a0<a href=\"https:\/\/2016.sevilla.wordcamp.org\/2016\/09\/15\/segundo-dia-de-wcsevilla16\/\" target=\"_blank\">segundo d\u00eda de #WCSevilla16<\/a>\u00a0y el\u00a0<a href=\"https:\/\/wp.me\/p72Uuo-nD\" target=\"_blank\">inicio del s\u00e1bado en el Liceo<\/a>. Y como ya \u00a0anunciamos en el\u00a0<a href=\"https:\/\/2016.sevilla.wordcamp.org\/2016\/09\/02\/avance-del-programa\/\" target=\"_blank\">avance del programa<\/a>\u00a0os tendremos un <strong>\u00c1gora<\/strong>, un <strong>Liceo<\/strong> y una <strong>Academia<\/strong> para disfrutar y adquirir conocimientos. \u00bfC\u00f3mo empezar\u00e1 el segundo d\u00eda de #WCSevilla16\u00a0en la <strong>Acamedia<\/strong>?<\/p>\n<p>A las <strong>diez<\/strong>\u00a0de la ma\u00f1ana,\u00a0<a href=\"https:\/\/2016.sevilla.wordcamp.org\/ponentes\/#wcorg-speaker-felix-zapata\">F\u00e9lix Zapata<\/a>\u00a0van a\u00a0presentar su <a href=\"https:\/\/2016.sevilla.wordcamp.org\/session\/taller-para-ensenar-como-detectar-fallos-comunes-de-accesibilidad-en-un-theme-y-ensenar-como-corregirlos\/\" target=\"_blank\">taller\u00a0para ense\u00f1ar c\u00f3mo detectar fallos comunes de accesibilidad en un theme y ense\u00f1ar c\u00f3mo corregirlos<\/a>, no te olvides de que durar\u00e1 una hora.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a1Recuerda\u00a0comprar tu <a href=\"https:\/\/2016.sevilla.wordcamp.org\/compra-tu-entrada\/\" target=\"_blank\">entrada<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfDespu\u00e9s del fin de semana ya te has decidido venir a WordCamp Sevilla 2016? Revisa\u00a0el programa\u00a0y aprovecha\u00a0la oportunidad. Como ya comentamos a finales de semana c\u00f3mo ser\u00e1 el\u00a0segundo d\u00eda de #WCSevilla16\u00a0y el\u00a0inicio del s\u00e1bado en el Liceo. Y como ya \u00a0anunciamos en el\u00a0avance del programa\u00a0os tendremos un \u00c1gora, un Liceo y una Academia para disfrutar &hellip; <a href=\"https:\/\/sevilla.wordcamp.org\/2016\/segundo-dia-de-wcsevilla16-en-la-academia\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Segundo d\u00eda de #WCSevilla16 en la Academia<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":13286167,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10659,943237],"tags":[],"class_list":["post-1499","post","type-post","status-publish","format-standard","hentry","category-ponencias","category-wordcamp2016"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p72Uuo-ob","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/1499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/13286167"}],"replies":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=1499"}],"version-history":[{"count":1,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/1499\/revisions"}],"predecessor-version":[{"id":1500,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/1499\/revisions\/1500"}],"wp:attachment":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=1499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/categories?post=1499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/tags?post=1499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}