{"id":393,"date":"2016-07-30T12:06:50","date_gmt":"2016-07-30T10:06:50","guid":{"rendered":"https:\/\/2016.sevilla.wordcamp.org\/?p=393"},"modified":"2016-07-28T12:16:27","modified_gmt":"2016-07-28T10:16:27","slug":"aunque-no-sepa-manejar-wordpress-puedo-asistir-a-la-wordcamp","status":"publish","type":"post","link":"https:\/\/sevilla.wordcamp.org\/2016\/aunque-no-sepa-manejar-wordpress-puedo-asistir-a-la-wordcamp\/","title":{"rendered":"\u00bfAunque no sepa manejar WordPress puedo asistir a la  WordCamp?"},"content":{"rendered":"<p>\u00a1Por supuesto! Este es el motivo por el que tienes que asistir.<\/p>\n<p>Sobre todo si acabas de terminar una formaci\u00f3n o estudios, quieres lanzarte al mundo online y no sabes como empezar. Si ya tienes tu WordPress lanzado este es tu evento. Conocer\u00e1s las ultimas tendencias, herramientas y a todos los profesionales del sector. All\u00ed podr\u00e1n ayudarte a solventar tus dudas. Pero si a\u00fan no tienes tu WordPress en marcha y no sabes ni como empezar, aqu\u00ed est\u00e1 tu sitio.<\/p>\n<p>Conocer\u00e1s los pasos b\u00e1sicos para comenzar. \u00bfQuieres hacerte un blog, una web corporativa, una tienda y no tienes ni idea de cu\u00e1l es el primer paso que tienes que dar?<\/p>\n<ol>\n<li>er paso- Asistir a la WordCamp en Sevilla.<\/li>\n<li>ndo paso- Pasear a tu bola por el evento y coger ideas y anotarlas.<\/li>\n<li>er paso- Detenerte donde m\u00e1s te interese e interactuar sin verg\u00fcenza, pregunta todo lo que se te ocurra, te ayudaran encantados. \u00a1Es tu momento!<\/li>\n<li>rto paso- Aprender\u00e1s tanto y de manera tan f\u00e1cil, que estar\u00e1s deseando darle forma a tus nuevos conocimientos.<\/li>\n<li>nto paso- Ya est\u00e1s dentro, solo te queda sentarse delante de tu m\u00e1quina. \u00a1\u00a1Bienvenid@!!<\/li>\n<\/ol>\n<p>Ahhh se me olvidada, el \u00fanico requisito que tienes que traer a un evento wordpressero son muchas ganas de aprender, del resto ya se ocupan otros.<br \/>\n\u00a1Cr\u00e9eme!<\/p>\n<p>Chary S\u00e1nchez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Por supuesto! Este es el motivo por el que tienes que asistir. Sobre todo si acabas de terminar una formaci\u00f3n o estudios, quieres lanzarte al mundo online y no sabes como empezar. Si ya tienes tu WordPress lanzado este es tu evento. Conocer\u00e1s las ultimas tendencias, herramientas y a todos los profesionales del sector. All\u00ed &hellip; <a href=\"https:\/\/sevilla.wordcamp.org\/2016\/aunque-no-sepa-manejar-wordpress-puedo-asistir-a-la-wordcamp\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">\u00bfAunque no sepa manejar WordPress puedo asistir a la  WordCamp?<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":7425830,"featured_media":394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[943237],"tags":[],"class_list":["post-393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wordcamp2016"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p72Uuo-6l","jetpack_featured_media_url":"https:\/\/sevilla.wordcamp.org\/2016\/files\/2016\/07\/instalar-WordPress-paso-5.png","_links":{"self":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/7425830"}],"replies":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=393"}],"version-history":[{"count":2,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/393\/revisions"}],"predecessor-version":[{"id":396,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/393\/revisions\/396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/media\/394"}],"wp:attachment":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/categories?post=393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/tags?post=393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}