{"id":498,"date":"2016-08-20T16:56:15","date_gmt":"2016-08-20T14:56:15","guid":{"rendered":"https:\/\/2016.sevilla.wordcamp.org\/?p=498"},"modified":"2016-08-13T16:57:36","modified_gmt":"2016-08-13T14:57:36","slug":"gracias-a-woocommerce-por-patrocinar-wordcamp-sevilla-2016","status":"publish","type":"post","link":"https:\/\/sevilla.wordcamp.org\/2016\/gracias-a-woocommerce-por-patrocinar-wordcamp-sevilla-2016\/","title":{"rendered":"Gracias a WooCommerce por patrocinar WordCamp Sevilla 2016"},"content":{"rendered":"<p>WooCommerce es software\/plataforma de comercio electr\u00f3nico que crece m\u00e1s r\u00e1pido. La usan m\u00e1s del 30% de todas las tiendas de comercio electr\u00f3nico, con m\u00e1s de 1 mill\u00f3n de instalaciones activas. Est\u00e1 construido para integrarse perfectamente con WordPress, por lo que es la elecci\u00f3n obvia de comercio electr\u00f3nico para los usuarios de WordPress. Se conecta con el ecosistema de WordPress, que est\u00e1\u00a0en\u00a0r\u00e1pido crecimiento: ahora est\u00e1 presente\u00a0en m\u00e1s de 25% de todos los sitios web de\u00a0Internet.<\/p>\n<p>Con WooCommerce puede empezar con todas las herramientas b\u00e1sicas que\u00a0cualquier peque\u00f1a empresa necesita para empezar a vender en l\u00ednea, como\u00a0la configuraci\u00f3n del producto, los pagos, las opciones de env\u00edo y los informes de ventas que indican que\u00a0tu negocio crece. Se puede elegir entre m\u00e1s de 300 complementos disponibles, como\u00a0procesos de pago adicionales, m\u00e9todos de env\u00edo, sistemas de inventario y herramientas de marketing para vender cualquier cosa y en cualquier lugar, productos reales y descargas digitales\u00a0de suscripciones, contenido e incluso tu tiempo.<\/p>\n<p>En julio de 2015, WooCommerce fue adquirida por Automattic, los creadores de <a href=\"https:\/\/wordpress.com\/\">WordPress.com<\/a> que mueven\u00a0m\u00e1s de 15,8 mil millones de p\u00e1ginas al mes y son tambi\u00e9n los creadores de otros servicios populares como WordPress Akismet, Jetpack y VaultPress. Esperamos con inter\u00e9s creciente como WooCommerce se hace\u00a0a\u00fan m\u00e1s grande con Automattic.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WooCommerce es software\/plataforma de comercio electr\u00f3nico que crece m\u00e1s r\u00e1pido. La usan m\u00e1s del 30% de todas las tiendas de comercio electr\u00f3nico, con m\u00e1s de 1 mill\u00f3n de instalaciones activas. Est\u00e1 construido para integrarse perfectamente con WordPress, por lo que es la elecci\u00f3n obvia de comercio electr\u00f3nico para los usuarios de WordPress. Se conecta con &hellip; <a href=\"https:\/\/sevilla.wordcamp.org\/2016\/gracias-a-woocommerce-por-patrocinar-wordcamp-sevilla-2016\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Gracias a WooCommerce por patrocinar WordCamp Sevilla 2016<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":7425830,"featured_media":147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10640],"tags":[946926],"class_list":["post-498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-patrocinadores","tag-nivel-superadmin"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p72Uuo-82","jetpack_featured_media_url":"https:\/\/sevilla.wordcamp.org\/2016\/files\/2016\/05\/woocommerce_logo.png","_links":{"self":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/7425830"}],"replies":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=498"}],"version-history":[{"count":1,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/498\/revisions"}],"predecessor-version":[{"id":499,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/498\/revisions\/499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/media\/147"}],"wp:attachment":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/categories?post=498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/tags?post=498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}