{"id":766,"date":"2016-09-08T12:06:13","date_gmt":"2016-09-08T10:06:13","guid":{"rendered":"https:\/\/2016.sevilla.wordcamp.org\/?p=766"},"modified":"2016-09-16T01:27:21","modified_gmt":"2016-09-15T23:27:21","slug":"mas-sobre-la-famosa-instalacion-en-30-minutos-de-wordpress","status":"publish","type":"post","link":"https:\/\/sevilla.wordcamp.org\/2016\/mas-sobre-la-famosa-instalacion-en-30-minutos-de-wordpress\/","title":{"rendered":"M\u00e1s sobre la famosa instalaci\u00f3n en 30 minutos de WordPress"},"content":{"rendered":"<p>Cada actualizaci\u00f3n de WordPress nos hace la vida m\u00e1s f\u00e1cil. Adem\u00e1s, contamos cada vez con m\u00e1s recursos disponibles para tener la instalaci\u00f3n que se ajusta a nuestro proyecto.<\/p>\n<p>Si alguna vez has instalado WordPress conocer\u00e1s su famosa instalaci\u00f3n en 5 minutos. Cierto es\u00a0que una vez instalado podr\u00edas ponerte a escribir directamente, pero \u00bfdebes quedarte ah\u00ed?<\/p>\n<p>Precisamente, \u00a0<a href=\"https:\/\/2016.sevilla.wordcamp.org\/speaker\/pablo-lopez\/\">Pablo L\u00f3pez<\/a>\u00a0nos\u00a0mostrar\u00e1 en este <a href=\"https:\/\/2016.sevilla.wordcamp.org\/session\/la-famosa-instalacion-en-30-minutos\/\" target=\"_blank\">taller<\/a> que,\u00a0si bien esto es cierto y\u00a0puedes pensar que con esto ya es suficiente, \u00a0c\u00f3mo puedes complementar esta instalaci\u00f3n, configuraciones avanzadas, mejorar la seguridad y optimizar el\u00a0rendimiento de nuestro sitio.<\/p>\n<p>Veremos c\u00f3mo dedic\u00e1ndole un poco m\u00e1s de tiempo a la instalaci\u00f3n de nuestro WordPress tendremos un sitio mejor, m\u00e1s trabajado, m\u00e1s r\u00e1pido y m\u00e1s seguro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada actualizaci\u00f3n de WordPress nos hace la vida m\u00e1s f\u00e1cil. Adem\u00e1s, contamos cada vez con m\u00e1s recursos disponibles para tener la instalaci\u00f3n que se ajusta a nuestro proyecto. Si alguna vez has instalado WordPress conocer\u00e1s su famosa instalaci\u00f3n en 5 minutos. Cierto es\u00a0que una vez instalado podr\u00edas ponerte a escribir directamente, pero \u00bfdebes quedarte ah\u00ed? &hellip; <a href=\"https:\/\/sevilla.wordcamp.org\/2016\/mas-sobre-la-famosa-instalacion-en-30-minutos-de-wordpress\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">M\u00e1s sobre la famosa instalaci\u00f3n en 30 minutos de WordPress<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":11274997,"featured_media":1474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10659,943237],"tags":[],"class_list":["post-766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ponencias","category-wordcamp2016"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p72Uuo-cm","jetpack_featured_media_url":"https:\/\/sevilla.wordcamp.org\/2016\/files\/2016\/09\/Pablo-1.jpg","_links":{"self":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/11274997"}],"replies":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=766"}],"version-history":[{"count":7,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/766\/revisions"}],"predecessor-version":[{"id":1199,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/766\/revisions\/1199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/media\/1474"}],"wp:attachment":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/categories?post=766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/tags?post=766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}