{"id":968,"date":"2016-09-06T12:50:58","date_gmt":"2016-09-06T10:50:58","guid":{"rendered":"https:\/\/2016.sevilla.wordcamp.org\/?post_type=wcb_session&#038;p=968"},"modified":"2016-09-06T12:51:25","modified_gmt":"2016-09-06T10:51:25","slug":"dockers-y-wordpress","status":"publish","type":"wcb_session","link":"https:\/\/sevilla.wordcamp.org\/2016\/session\/dockers-y-wordpress\/","title":{"rendered":"Dockers y WordPress (1 hora)"},"content":{"rendered":"<p>Dockers y WordPress, Dockers es una plataforma para el desarrollo, transporte y ejecuci\u00f3n de Aplicaciones, la ventaja de Dockers radica en que podremos envasar el entorno que deseamos para entregar de forma mas r\u00e1pida y sin c\u00f3digos innecesarios nuestros proyectos y Aplicaciones. Podremos administrar nuestra infraestructura por separado, garantizando el uso de los recursos necesarios al ejecutar nuestra Aplicaci\u00f3n. Podremos realizar pruebas en diferentes entornos a nuestros proyectos sin la necesidad de tener que realizar instalaciones adicionales a nuestro entorno b\u00e1sico. Haremos una breve rese\u00f1a de Dockers, su historia, sus usos. Aprenderemos a crear un contenedor para nuestra aplicaci\u00f3n en WordPress y podremos observar las ventajas que nos brinda. Haremos una prueba en vivo de como usar un Dockers para tu entorno de desarrollo con WordPress.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dockers y WordPress, Dockers es una plataforma para el desarrollo, transporte y ejecuci\u00f3n de Aplicaciones, la ventaja de Dockers radica en que podremos envasar el entorno que deseamos para entregar de forma mas r\u00e1pida y sin c\u00f3digos innecesarios nuestros proyectos y Aplicaciones. Podremos administrar nuestra infraestructura por separado, garantizando el uso de los recursos necesarios &hellip; <a href=\"https:\/\/sevilla.wordcamp.org\/2016\/session\/dockers-y-wordpress\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Dockers y WordPress (1 hora)<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":14411924,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1475316000,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[979],"footnotes":""},"session_track":[946930],"session_category":[],"class_list":["post-968","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-academia"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p72Uuo-fC","session_date_time":{"date":"01\/10\/2016","time":"12:00"},"session_speakers":[],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":4,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/968\/revisions"}],"predecessor-version":[{"id":1059,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/968\/revisions\/1059"}],"speakers":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/979"}],"author":[{"embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wporg\/v1\/users\/anonymized-14411924"}],"wp:attachment":[{"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=968"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/session_track?post=968"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/sevilla.wordcamp.org\/2016\/wp-json\/wp\/v2\/session_category?post=968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}